{"id":3,"date":"2023-07-05T13:00:08","date_gmt":"2023-07-05T13:00:08","guid":{"rendered":"https:\/\/aeboaagua.org\/erasmusboaagua\/?page_id=3"},"modified":"2023-07-05T18:08:24","modified_gmt":"2023-07-05T18:08:24","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/aeboaagua.org\/erasmusboaagua\/privacy-policy\/","title":{"rendered":"PRIVACY POLICY"},"content":{"rendered":"\r\n<h3 class=\"wp-block-heading\">Quem n\u00f3s somos<\/h3>\r\n<p>O endere\u00e7o do nosso site \u00e9: https:\/\/aeboaagua.org\/ebiba.<\/p>\r\n<h3>Coment\u00e1rios<\/h3>\r\n<p>Quando os visitantes deixam coment\u00e1rios no site, coletamos os dados mostrados no formul\u00e1rio de coment\u00e1rios, e tamb\u00e9m o endere\u00e7o IP do visitante e a string do agente do usu\u00e1rio do navegador para ajudar na detec\u00e7\u00e3o de spam.<\/p>\r\n<p>Uma string an\u00f4nima criada a partir do seu endere\u00e7o de e-mail (tamb\u00e9m chamada de hash) pode ser fornecida ao servi\u00e7o Gravatar para verificar se voc\u00ea a est\u00e1 usando. A pol\u00edtica de privacidade do servi\u00e7o Gravatar est\u00e1 dispon\u00edvel aqui: https:\/\/automattic.com\/privacy\/. Ap\u00f3s a aprova\u00e7\u00e3o do seu coment\u00e1rio, a foto do seu perfil fica vis\u00edvel ao p\u00fablico no contexto do seu coment\u00e1rio.<\/p>\r\n<h3>Media<\/h3>\r\n<p>Se voc\u00ea enviar imagens para o site, evite enviar imagens com dados de localiza\u00e7\u00e3o incorporados (EXIF GPS) inclu\u00eddos. Os visitantes do site podem baixar e extrair quaisquer dados de localiza\u00e7\u00e3o das imagens no site.<\/p>\r\n<h3>Cookies<\/h3>\r\n<p>Se voc\u00ea deixar um coment\u00e1rio em nosso site, poder\u00e1 optar por salvar seu nome, endere\u00e7o de e-mail e site nos cookies. Estes s\u00e3o para sua conveni\u00eancia, para que voc\u00ea n\u00e3o precise preencher seus dados novamente quando deixar outro coment\u00e1rio. Esses cookies duram um ano.<\/p>\r\n<p>Se voc\u00ea visitar nossa p\u00e1gina de login, definiremos um cookie tempor\u00e1rio para determinar se seu navegador aceita cookies. Este cookie n\u00e3o cont\u00e9m dados pessoais e \u00e9 descartado quando voc\u00ea fecha o navegador.<\/p>\r\n<p>Quando voc\u00ea fizer login, tamb\u00e9m configuraremos v\u00e1rios cookies para salvar suas informa\u00e7\u00f5es de login e suas op\u00e7\u00f5es de exibi\u00e7\u00e3o na tela. Os cookies de login duram dois dias e os cookies de op\u00e7\u00f5es de tela duram um ano. Se voc\u00ea selecionar &#8220;Lembrar-me&#8221;, seu login persistir\u00e1 por duas semanas. Se voc\u00ea sair da sua conta, os cookies de login ser\u00e3o removidos.<\/p>\r\n<p>Se voc\u00ea editar ou publicar um artigo, um cookie adicional ser\u00e1 salvo em seu navegador. Este cookie n\u00e3o inclui dados pessoais e simplesmente indica o ID da postagem do artigo que voc\u00ea acabou de editar. Expira ap\u00f3s 1 dia.<\/p>\r\n<h3>Conte\u00fado incorporado de outros sites<\/h3>\r\n<p>Os artigos deste site podem incluir conte\u00fado incorporado (por exemplo, v\u00eddeos, imagens, artigos, etc.). O conte\u00fado incorporado de outros sites se comporta exatamente da mesma maneira como se o visitante tivesse visitado o outro site.<\/p>\r\n<p>Esses sites podem coletar dados sobre voc\u00ea, usar cookies, incorporar rastreamento adicional de terceiros e monitorar sua intera\u00e7\u00e3o com esse conte\u00fado incorporado, incluindo o rastreamento de sua intera\u00e7\u00e3o com o conte\u00fado incorporado se voc\u00ea tiver uma conta e estiver conectado a esse site.<\/p>\r\n<h3>Com quem compartilhamos seus dados<\/h3>\r\n<p>Se voc\u00ea solicitar uma redefini\u00e7\u00e3o de senha, seu endere\u00e7o IP ser\u00e1 inclu\u00eddo no e-mail de redefini\u00e7\u00e3o.<\/p>\r\n<h3>Por quanto tempo retemos seus dados<\/h3>\r\n<p>Se voc\u00ea deixar um coment\u00e1rio, o coment\u00e1rio e seus metadados ser\u00e3o retidos indefinidamente. Isso \u00e9 para que possamos reconhecer e aprovar quaisquer coment\u00e1rios de acompanhamento automaticamente, em vez de mant\u00ea-los em uma fila de modera\u00e7\u00e3o.<\/p>\r\n<p>Para usu\u00e1rios que se registram em nosso site (se houver), tamb\u00e9m armazenamos as informa\u00e7\u00f5es pessoais que eles fornecem em seu perfil de usu\u00e1rio. Todos os usu\u00e1rios podem ver, editar ou excluir suas informa\u00e7\u00f5es pessoais a qualquer momento (exceto que n\u00e3o podem alterar seu nome de usu\u00e1rio). Os administradores do site tamb\u00e9m podem ver e editar essas informa\u00e7\u00f5es.<\/p>\r\n<h3>Quais direitos voc\u00ea tem sobre seus dados<\/h3>\r\n<p>Se voc\u00ea possui uma conta neste site ou deixou coment\u00e1rios, pode solicitar o recebimento de um arquivo exportado dos dados pessoais que mantemos sobre voc\u00ea, incluindo quaisquer dados que voc\u00ea nos forneceu. Voc\u00ea tamb\u00e9m pode solicitar que apaguemos quaisquer dados pessoais que mantemos sobre voc\u00ea. Isso n\u00e3o inclui quaisquer dados que somos obrigados a manter para fins administrativos, legais ou de seguran\u00e7a.<\/p>\r\n<h3>Para onde seus dados s\u00e3o enviados<\/h3>\r\n<p>Os coment\u00e1rios dos visitantes podem ser verificados por meio de um servi\u00e7o automatizado de detec\u00e7\u00e3o de spam.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Quem n\u00f3s somos O endere\u00e7o do nosso site \u00e9: https:\/\/aeboaagua.org\/ebiba. Coment\u00e1rios Quando os visitantes deixam coment\u00e1rios no site, coletamos os dados mostrados no formul\u00e1rio de coment\u00e1rios, e tamb\u00e9m o endere\u00e7o IP do visitante e a string do agente do usu\u00e1rio do navegador para ajudar na detec\u00e7\u00e3o de spam. Uma string an\u00f4nima criada a partir do &hellip; <\/p>\n<div class=\"link-more\"><a href=\"https:\/\/aeboaagua.org\/erasmusboaagua\/privacy-policy\/\" class=\"more-link\">Read More<span class=\"screen-reader-text\"> &#8220;PRIVACY POLICY&#8221;<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/aeboaagua.org\/erasmusboaagua\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aeboaagua.org\/erasmusboaagua\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aeboaagua.org\/erasmusboaagua\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aeboaagua.org\/erasmusboaagua\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeboaagua.org\/erasmusboaagua\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":3,"href":"https:\/\/aeboaagua.org\/erasmusboaagua\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":291,"href":"https:\/\/aeboaagua.org\/erasmusboaagua\/wp-json\/wp\/v2\/pages\/3\/revisions\/291"}],"wp:attachment":[{"href":"https:\/\/aeboaagua.org\/erasmusboaagua\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}